{"id":699,"date":"2022-03-05T22:27:00","date_gmt":"2022-03-05T21:27:00","guid":{"rendered":"https:\/\/www.cbciudaddecadiz.com\/?p=699"},"modified":"2022-03-10T12:40:26","modified_gmt":"2022-03-10T11:40:26","slug":"gran-imagen-de-nuestras-infantiles-en-el-derbi-ante-el-gades","status":"publish","type":"post","link":"https:\/\/www.cbciudaddecadiz.com\/index.php\/2022\/03\/05\/gran-imagen-de-nuestras-infantiles-en-el-derbi-ante-el-gades\/","title":{"rendered":"Gran imagen de nuestras infantiles en el derbi ante el C\u00e1diz CB Gades"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jornada 13 de la competici\u00f3n federada para nuestras infantiles que recibieron al C\u00e1diz CB Gades, cuarto clasificado en la liga y equipo que en la ida nos cerr\u00f3 el acta a comienzos del tercer periodo con el resultado de 58-8.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestras chicas entraron bien en el partido, aunque el habitual desacierto en las finalizaciones, debido a la precipitaci\u00f3n, no nos permit\u00eda mantenernos pegadas en el marcador y el primer periodo finalizaba con ventaja para un Gades, que al igual que en la ida nos someti\u00f3 a una presi\u00f3n asfixiante durante todo el encuentro, con la diferencia de que esta vez nuestras chicas fueron capaces de afrontar con bastante acierto esa presi\u00f3n (6-13).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el segundo periodo nuestras chicas sufrieron un fuerte cortocircuito en ataque y aunque sal\u00edamos bien de la presi\u00f3n, no culmin\u00e1bamos las jugadas con p\u00e9rdidas de bal\u00f3n y contras del rival, lo que permiti\u00f3 a un buen equipo, como el Gades, adquirir una c\u00f3moda ventaja de 7 a 25 al descanso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el descanso, nuestras chicas tuvieron una gran reacci\u00f3n y jugaron en todo momento de tu a tu ante un gran rival que nos castigaba cada vez que ten\u00edamos el m\u00e1s m\u00ednimo error, as\u00ed, la ventaja del Gades no creci\u00f3 mucho m\u00e1s y el encuentro finaliz\u00f3 con victoria visitante por el resultado de 22 a 45.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez m\u00e1s, nuestras chicas muestran una gran mejor\u00eda respecto al partido de la primera vuelta, pasando de perder con acta cerrada en el tercer periodo en la ida, a perder de tan solo 23 puntos en la vuelta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Felicitamos al C\u00e1diz CB Gades por su victoria y a nuestras chicas por la evoluci\u00f3n que se est\u00e1 viendo partido tras partido, lo que le est\u00e1 llevando a plantar cara a equipos que en la primera vuelta se mostraron muy superiores. \u00a1\u00a1Enhorabuena chicas!! \u00a1\u00a1Gran trabajo!!<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\">Resultado final: CBC C\u00e1diz <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">22<\/mark>&#8211;<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">45<\/mark> C\u00e1diz CB Gades<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Jornada 13 de la competici\u00f3n federada para nuestras infantiles que recibieron al C\u00e1diz CB Gades, cuarto clasificado en la liga y equipo que en la ida nos cerr\u00f3 el acta a comienzos del tercer periodo con el resultado de 58-8. Nuestras chicas entraron bien en el partido, aunque el habitual desacierto en las finalizaciones, debido&#8230;<\/p>\n","protected":false},"author":1,"featured_media":679,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[16,27,9],"tags":[14,13,7,8],"class_list":["post-699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronicas-cbc-cadiz","category-infantil-femenino-del-club-baloncesto-ciudad-de-cadiz","category-noticias-cbc-cadiz","tag-baloncesto-cadiz","tag-cb-ciudad-de-cadiz","tag-cbc-cadiz","tag-club-baloncesto-ciudad-de-cadiz"],"uagb_featured_image_src":{"full":["https:\/\/www.cbciudaddecadiz.com\/wp-content\/uploads\/2022\/03\/20211211_111913.jpg",1000,750,false],"thumbnail":["https:\/\/www.cbciudaddecadiz.com\/wp-content\/uploads\/2022\/03\/20211211_111913-150x150.jpg",150,150,true],"medium":["https:\/\/www.cbciudaddecadiz.com\/wp-content\/uploads\/2022\/03\/20211211_111913-300x225.jpg",300,225,true],"medium_large":["https:\/\/www.cbciudaddecadiz.com\/wp-content\/uploads\/2022\/03\/20211211_111913-768x576.jpg",768,576,true],"large":["https:\/\/www.cbciudaddecadiz.com\/wp-content\/uploads\/2022\/03\/20211211_111913.jpg",1000,750,false],"1536x1536":["https:\/\/www.cbciudaddecadiz.com\/wp-content\/uploads\/2022\/03\/20211211_111913.jpg",1000,750,false],"2048x2048":["https:\/\/www.cbciudaddecadiz.com\/wp-content\/uploads\/2022\/03\/20211211_111913.jpg",1000,750,false]},"uagb_author_info":{"display_name":"CBC C\u00e1diz","author_link":"https:\/\/www.cbciudaddecadiz.com\/index.php\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Jornada 13 de la competici\u00f3n federada para nuestras infantiles que recibieron al C\u00e1diz CB Gades, cuarto clasificado en la liga y equipo que en la ida nos cerr\u00f3 el acta a comienzos del tercer periodo con el resultado de 58-8. Nuestras chicas entraron bien en el partido, aunque el habitual desacierto en las finalizaciones, debido...","_links":{"self":[{"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/posts\/699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/comments?post=699"}],"version-history":[{"count":3,"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/posts\/699\/revisions"}],"predecessor-version":[{"id":727,"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/posts\/699\/revisions\/727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/media\/679"}],"wp:attachment":[{"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/media?parent=699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/categories?post=699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cbciudaddecadiz.com\/index.php\/wp-json\/wp\/v2\/tags?post=699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}